{"id":39,"date":"2024-07-15T21:52:39","date_gmt":"2024-07-15T19:52:39","guid":{"rendered":"https:\/\/kirizaki.it\/?page_id=39"},"modified":"2026-02-04T23:27:07","modified_gmt":"2026-02-04T22:27:07","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/kirizaki.it\/index.php\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"\n<p>Il desiderio di dare vita all&#8217;Associazione Culturale Kirizaki \u00e8 nato a Berbenno (SO) l&#8217;11 Marzo 2024 come espressione della volont\u00e0, condivisa dai <a href=\"https:\/\/kirizaki.it\/index.php\/chi-siamo\/organigramma\/\" data-type=\"page\" data-id=\"113\">Soci Fondatori<\/a>, di voler promulgare la cultura giapponese in Italia attraverso l&#8217;arte, con particolare riguardo alla Danza Tradizionale Giapponese Zashiki-mai.<\/p>\n\n\n\n<p>I soci fondatori hanno potuto conoscere la danza <a href=\"https:\/\/kirizaki.it\/index.php\/attivita\/danza\/\" data-type=\"page\" data-id=\"176\">Zashiki-mai<\/a> solo grazie alla profonda amicizia che, da oltre dieci anni, li lega con la signora Kirizaki Tsurujo, docente a T\u014dky\u014d di questa nobile arte dal 1999.<\/p>\n\n\n\n<p>Da sempre appassionati di cultura giapponese, amici di una vita, non \u00e8 stato difficile per i Soci fondatori trovarsi al tavolo e decidere, con coraggio, di dedicarsi in prima persona alla creazione di un ponte che potesse mettere in contatto i nostri concittadini con le arti pi\u00f9 tradizionali del Giappone.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il desiderio di dare vita all&#8217;Associazione Culturale Kirizaki \u00e8 nato a Berbenno (SO) l&#8217;11 Marzo 2024 come espressione della volont\u00e0, condivisa dai Soci Fondatori, di voler promulgare la cultura giapponese in Italia attraverso l&#8217;arte, con particolare riguardo alla Danza Tradizionale Giapponese Zashiki-mai. I soci fondatori hanno potuto conoscere la danza Zashiki-mai solo grazie alla profonda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-39","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":6,"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":583,"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions\/583"}],"wp:attachment":[{"href":"https:\/\/kirizaki.it\/index.php\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}